{"id":52578,"date":"2026-02-03T12:04:42","date_gmt":"2026-02-03T12:04:42","guid":{"rendered":"https:\/\/hostify.com\/events\/scale-middle-east-2026"},"modified":"2026-02-19T09:26:50","modified_gmt":"2026-02-19T09:26:50","slug":"scale-middle-east-2026","status":"publish","type":"events","link":"https:\/\/hostify.com\/fr\/events\/scale-middle-east-2026","title":{"rendered":"SCALE Middle East 2026"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"52578\" class=\"elementor elementor-52578 elementor-52561\" data-elementor-post-type=\"events\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66e94181 e-flex e-con-boxed e-con e-parent\" data-id=\"66e94181\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-354156f6 e-con-full e-flex e-con e-child\" data-id=\"354156f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8bb57 elementor-widget elementor-widget-heading\" data-id=\"c8bb57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Rencontrez l\u2019\u00e9quipe Hostify \u00e0 SCALE Middle East 2026\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ad49d0a elementor-widget elementor-widget-text-editor\" data-id=\"4ad49d0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nous sommes ravis d\u2019annoncer que Hostify participera \u00e0 SCALE Middle East 2026, l\u2019un des principaux \u00e9v\u00e9nements d\u00e9di\u00e9s \u00e0 la location de courte dur\u00e9e dans l\u2019une des r\u00e9gions les plus dynamiques et comp\u00e9titives au monde, qui se tiendra \u00e0 Duba\u00ef.<\/span><\/p><p><span style=\"font-weight: 400;\">Rejoignez nous pour d\u00e9couvrir comment l\u2019innovation, la r\u00e9glementation et la technologie fa\u00e7onnent l\u2019avenir de la location de courte dur\u00e9e au Moyen Orient, et pour \u00e9changer avec des leaders du secteur engag\u00e9s dans le d\u00e9veloppement d\u2019op\u00e9rations sur un march\u00e9 \u00e0 forte croissance.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-768b3731 elementor-align-left elementor-widget elementor-widget-post-info\" data-id=\"768b3731\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-dd9961c elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\t30\/09\/2026\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-130bb286 e-con-full e-flex e-con e-child\" data-id=\"130bb286\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23a1bb45 elementor-widget elementor-widget-image\" data-id=\"23a1bb45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"764\" height=\"282\" src=\"https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/logo-scale-ME-2025.svg\" class=\"attachment-full size-full wp-image-52563\" alt=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32ef186a e-flex e-con-boxed e-con e-parent\" data-id=\"32ef186a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2dea7e21 e-con-full e-flex e-con e-child\" data-id=\"2dea7e21\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51ee39e1 elementor-widget elementor-widget-heading\" data-id=\"51ee39e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">R\u00e9servez une r\u00e9union.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ecc951b elementor-widget elementor-widget-html\" data-id=\"1ecc951b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/embed\/v2.js\"><\/script><script>hbspt.forms.create({\r\n    portalId: \"5828152\",\r\n    formId: \"96005b95-4a3d-4a0a-88ab-58728a499e52\",\r\n    region: \"na1\"\r\n  });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ad6229d e-con-full e-flex e-con e-child\" data-id=\"1ad6229d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1be05d1c elementor-widget elementor-widget-heading\" data-id=\"1be05d1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment nous trouver<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d49649d elementor-widget elementor-widget-google_maps\" data-id=\"d49649d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Hilton%20Dubai%20Palm%20Jumeirah&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Hilton Dubai Palm Jumeirah\"\n\t\t\t\t\taria-label=\"Hilton Dubai Palm Jumeirah\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23cd0864 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"23cd0864\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 64h-48V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H160V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H48C21.5 64 0 85.5 0 112v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V112c0-26.5-21.5-48-48-48zm-6 400H54c-3.3 0-6-2.7-6-6V160h352v298c0 3.3-2.7 6-6 6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 septembre 2026 au 1 octobre 2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hilton Palm Jumeirah Dubai, United Arab Emirates<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Booth number: 24<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7158853 e-flex e-con-boxed e-con e-parent\" data-id=\"7158853\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dfc713d e-con-full e-flex e-con e-child\" data-id=\"dfc713d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c1fcf0 elementor-widget elementor-widget-heading\" data-id=\"8c1fcf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c0 propos de l'\u00e9v\u00e9nement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9207887 elementor-widget elementor-widget-text-editor\" data-id=\"9207887\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">SCALE Middle East 2026 revient \u00e0 Duba\u00ef comme un point de rencontre incontournable pour les gestionnaires de biens, les investisseurs et les entrepreneurs op\u00e9rant dans le secteur de la location de courte dur\u00e9e.<\/span><\/p><p><span style=\"font-weight: 400;\">Alors que la r\u00e9gion continue de se positionner comme une puissance mondiale du tourisme, l\u2019\u00e9v\u00e9nement met l\u2019accent sur l\u2019accompagnement des op\u00e9rateurs afin qu\u2019ils restent en avance sur les enjeux d\u2019innovation et de r\u00e9glementation. Sur deux journ\u00e9es, les participants b\u00e9n\u00e9ficieront d\u2019analyses strat\u00e9giques, d\u00e9couvriront des solutions technologiques avanc\u00e9es et construiront des partenariats locaux et internationaux \u00e0 forte valeur ajout\u00e9e pour soutenir une croissance durable. <\/span><\/p><p><span style=\"font-weight: 400;\">La conf\u00e9rence r\u00e9unit des voix influentes de l\u2019ensemble du secteur afin d\u2019aborder les sp\u00e9cificit\u00e9s r\u00e9gionales et de fournir des recommandations pratiques pour se d\u00e9velopper dans un environnement hautement concurrentiel.<\/span><\/p><p><strong>\u00c0 quoi s&rsquo;attendre :<\/strong><\/p><p><span style=\"font-weight: 400;\">Sur deux journ\u00e9es intensives, SCALE Middle East 2026 proposera des contenus \u00e9ducatifs \u00e0 forte valeur ajout\u00e9e et des opportunit\u00e9s de networking soigneusement s\u00e9lectionn\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">L\u2019\u00e9v\u00e9nement comprendra :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Des sessions strat\u00e9giques anim\u00e9es par des experts r\u00e9gionaux et internationaux du secteur<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Un contenu fa\u00e7onn\u00e9 par les retours des participants et les besoins op\u00e9rationnels r\u00e9els<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Des \u00e9changes centr\u00e9s sur l\u2019innovation, la r\u00e9glementation et la croissance des entreprises<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Un networking de haut niveau entre pairs avec des op\u00e9rateurs exp\u00e9riment\u00e9s<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Des opportunit\u00e9s de cr\u00e9er des partenariats favorisant une expansion \u00e0 long terme<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Cet \u00e9v\u00e9nement s\u2019adresse aux gestionnaires de biens professionnels et aux h\u00f4tes souhaitant d\u00e9velopper leurs activit\u00e9s de location de courte dur\u00e9e, am\u00e9liorer leur efficacit\u00e9, \u00e9largir leur portefeuille et accro\u00eetre leur rentabilit\u00e9. La participation est limit\u00e9e aux op\u00e9rateurs professionnels g\u00e9rant un minimum de dix unit\u00e9s. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e76cac3 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"e76cac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/middle-east.scalerentals.show\/event\/scale-middle-east-2026\/\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"14\" viewBox=\"0 0 23 14\" fill=\"none\"><path d=\"M15.0806 2.64164L18.4002 5.89267H1.875C1.25876 5.89267 0.75 6.3839 0.75 7C0.75 7.6161 1.25876 8.10733 1.875 8.10733H18.4004L15.0823 11.3584C14.641 11.7908 14.641 12.4954 15.0823 12.9278C15.5207 13.3574 16.231 13.3574 16.6695 12.9278L21.9195 7.78384C22.0232 7.68223 22.1072 7.5602 22.1642 7.42398L22.1655 7.42066C22.2173 7.29164 22.25 7.15024 22.25 7.00343V7.00341V7.00339V7.00337V7.00335V7.00333V7.00331V7.00329V7.00327V7.00325V7.00324V7.00322V7.0032V7.00318V7.00316V7.00314V7.00313V7.00311V7.00309V7.00307V7.00306V7.00304V7.00302V7.00301V7.00299V7.00297V7.00296V7.00294V7.00292V7.00291V7.00289V7.00288V7.00286V7.00284V7.00283V7.00281V7.0028V7.00278V7.00277V7.00275V7.00274V7.00272V7.00271V7.00269V7.00268V7.00267V7.00265V7.00263V7.00262V7.0026V7.00257V7.00255V7.00253V7.00251V7.00249V7.00248V7.00246V7.00244V7.00242V7.0024V7.00238V7.00236V7.00234V7.00233V7.00231V7.00229V7.00227V7.00225V7.00224V7.00222V7.0022V7.00219V7.00217V7.00215V7.00214V7.00212V7.0021V7.00209V7.00207V7.00205V7.00204V7.00202V7.00201V7.00199V7.00197V7.00196V7.00194V7.00193V7.00191V7.0019V7.00188V7.00187V7.00185V7.00184V7.00182V7.00181V7.00179V7.00178V7.00176V7.00174V7.00173V7.00171V7.0017V7.00168V7.00167V7.00165V7.00164V7.00162V7.00161V7.00159V7.00158V7.00156V7.00155V7.00153V7.00152V7.0015V7.00149V7.00147V7.00146V7.00144V7.00142V7.00141V7.00139V7.00138V7.00136V7.00134V7.00133V7.00131V7.00129V7.00128V7.00126V7.00124V7.00123V7.00121V7.00119V7.00118V7.00116V7.00114V7.00112V7.0011V7.00109V7.00107V7.00105V7.00103V7.00101V7.00099V7.00097V7.00095V7.00094V7.00092V7.0009V7.00087V7.00085V7.00083V7.00081V7.00079V7.00078V7.00076V7.00074V7.00073V7.00071V7.0007V7.00068V7.00067V7.00065V7.00064V7.00062V7.00061V7.00059V7.00058V7.00056V7.00055V7.00053V7.00051V7.0005V7.00048V7.00046V7.00045V7.00043V7.00041V7.0004V7.00038V7.00036V7.00035V7.00033V7.00031V7.00029V7.00028V7.00026V7.00024V7.00022V7.0002V7.00018V7.00017V7.00015V7.00013V7.00011V7.00009V7.00007V7.00005V7.00003V7.00001C22.25 6.85507 22.2205 6.71022 22.1617 6.5744C22.1047 6.43883 22.021 6.31736 21.9177 6.21616L16.6677 1.0722C16.2293 0.642601 15.519 0.642601 15.0805 1.0722C14.6392 1.50458 14.6392 2.20921 15.0805 2.6416L15.0806 2.64164Z\" fill=\"white\" stroke=\"white\" stroke-width=\"0.5\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenez vos billets<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88da0fd e-con-full e-flex e-con e-child\" data-id=\"88da0fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7be2a8 elementor-widget elementor-widget-image\" data-id=\"b7be2a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/DSC05993-1024x683.jpg\" class=\"attachment-large size-large wp-image-52568\" alt=\"\" srcset=\"https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/DSC05993-1024x683.jpg 1024w, https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/DSC05993-300x200.jpg 300w, https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/DSC05993-768x512.jpg 768w, https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/DSC05993-1536x1024.jpg 1536w, https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/DSC05993.jpg 1800w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf0b5e2 elementor-widget elementor-widget-image\" data-id=\"bf0b5e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"320\" src=\"https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/scale-middle-east-1024x409.png\" class=\"attachment-large size-large wp-image-53533\" alt=\"\" srcset=\"https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/scale-middle-east-1024x409.png 1024w, https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/scale-middle-east-300x120.png 300w, https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/scale-middle-east-768x307.png 768w, https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/scale-middle-east-1536x614.png 1536w, https:\/\/hostify.com\/wp-content\/uploads\/2026\/02\/scale-middle-east.png 1552w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SCALE Middle East 2026 revient \u00e0 Duba\u00ef comme un point de rencontre incontournable pour les gestionnaires de biens, les investisseurs et les entrepreneurs op\u00e9rant dans le secteur de la location de courte dur\u00e9e.<\/p>\n","protected":false},"author":3,"featured_media":52563,"template":"elementor_header_footer","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"event_type_tax":[239],"class_list":["post-52578","events","type-events","status-publish","has-post-thumbnail","hentry","event_type_tax-events"],"acf":[],"_links":{"self":[{"href":"https:\/\/hostify.com\/fr\/wp-json\/wp\/v2\/events\/52578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hostify.com\/fr\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/hostify.com\/fr\/wp-json\/wp\/v2\/types\/events"}],"author":[{"embeddable":true,"href":"https:\/\/hostify.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/hostify.com\/fr\/wp-json\/wp\/v2\/events\/52578\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hostify.com\/fr\/wp-json\/wp\/v2\/media\/52563"}],"wp:attachment":[{"href":"https:\/\/hostify.com\/fr\/wp-json\/wp\/v2\/media?parent=52578"}],"wp:term":[{"taxonomy":"event_type_tax","embeddable":true,"href":"https:\/\/hostify.com\/fr\/wp-json\/wp\/v2\/event_type_tax?post=52578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}